{"id":11934,"date":"2019-03-07T21:26:24","date_gmt":"2019-03-07T21:26:24","guid":{"rendered":"https:\/\/advbox.com.br\/blog\/?post_type=modelos&#038;p=11934"},"modified":"2025-12-24T10:03:17","modified_gmt":"2025-12-24T13:03:17","slug":"acao-de-nulidade-de-ato-juridico","status":"publish","type":"modelos","link":"https:\/\/advbox.com.br\/blog\/modelos\/acao-de-nulidade-de-ato-juridico\/","title":{"rendered":"Modelo de a\u00e7\u00e3o de nulidade de ato jur\u00eddico"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<h1 class=\"wp-block-heading\"><strong>MODELO DE A\u00c7\u00c3O DE NULIDADE DE ATO JUR\u00cdDICO<\/strong><\/h1>\n\n\n\n<p><span><strong>EXCELENT\u00cdSSIMO SENHOR DOUTOR JUIZ DE DIREITO DA VARA C\u00cdVEL DO FORO CENTRAL DA COMARCA DA REGI\u00c3O METROPOLITANA DE <\/strong><\/span><span><strong>&#8230;<\/strong><\/span><\/p>\n\n\n\n<p><span><strong>&#8230; (nome completo em negrito da parte)<\/strong><\/span><span>, &#8230; (nacionalidade), &#8230; (estado civil), &#8230; (profiss\u00e3o), portador do CPF\/MF n\u00ba &#8230;, com Documento de Identidade de n\u00b0 &#8230;, residente e domiciliado na <\/span><span>Rua &#8230;, n. &#8230;, &#8230; (bairro), CEP: &#8230;, &#8230; (Munic\u00edpio \u2013 UF)<\/span><span>, vem respeitosamente perante a Vossa Excel\u00eancia propor:<\/span><\/p>\n\n\n\n<p class=\"has-text-align-center\"><span><strong>A\u00c7\u00c3O DE NULIDADE DE ATO JUR\u00cdDICO C\/C CANCELAMENTO DE REGISTRO IMOBILI\u00c1RIO, IMISS\u00c3O DE POSSE, INDENIZA\u00c7\u00c3O POR DANOS MORAIS E TUTELA ANTECIPADA<\/strong><\/span><\/p>\n\n\n\n<p><span>em face de <\/span><span><strong>&#8230; (nome em negrito da parte)<\/strong><\/span><span>, &#8230; (indicar se \u00e9 pessoa f\u00edsica ou jur\u00eddica), com CPF\/CNPJ de n. &#8230;, com sede na Rua &#8230;, n. &#8230;, &#8230; (bairro), CEP: &#8230;, &#8230; (Munic\u00edpio\u2013 UF), pelas raz\u00f5es de fato e de direito que passa a aduzir e no final requer.:<\/span><\/p>\n\n\n\n<p><span><strong>I &#8211; DA JUSTI\u00c7A GRATUITA<\/strong><\/span><\/p>\n\n\n\n<p><span>1)<\/span><span><strong>&nbsp;<\/strong><\/span><span>Inicialmente declara a Requerente sob as penas da lei, que n\u00e3o possui recursos que lhe permitiam custear as despesas processuais e honor\u00e1rias advocat\u00edcias sem preju\u00edzo de seu pr\u00f3prio sustento, conforme se comprova da declara\u00e7\u00e3o de hipossufici\u00eancia juntada aos autos e por fim, declara ser aposentada recebendo um valor que n\u00e3o consegue custear as custas processuais tampouco honor\u00e1rios advocat\u00edcios.<\/span><\/p>\n\n\n\n<p><span>Por esse motivo requer o favorecimento da justi\u00e7a gratuita conforme preceitua o art.&nbsp;<\/span><span>4\u00ba<\/span><span>&nbsp;da Lei n\u00ba&nbsp;<\/span><span>1060<\/span><span>\/50 (com altera\u00e7\u00f5es da Lei n\u00ba&nbsp;<\/span><span>7.510<\/span><span>\/86), isentando-a de taxas judici\u00e1rias e demais custas processuais, indicando patrocinar a causa os advogados qualificados na procura\u00e7\u00e3o anexa, que declaram aceitar o encargo.<\/span><\/p>\n\n\n\n<p><span>\u00c1 luz da jurisprud\u00eancia pertinente:<\/span><\/p>\n\n\n\n<p><span><strong>&#8220;&#8230; \u00c9 suficiente para obten\u00e7\u00e3o do benef\u00edcio da assist\u00eancia judici\u00e1ria, a simples afirma\u00e7\u00e3o da parte de que n\u00e3o est\u00e1 em condi\u00e7\u00f5es de pagar as custas do processo e os honor\u00e1rios de advogados, sem preju\u00edzo do pr\u00f3prio ou de sua fam\u00edlia.&#8221; <\/strong><\/span><span><strong>[1]<\/strong><\/span><\/p>\n\n\n\n<p><span><strong>II\u2013 DOS FATOS<\/strong><\/span><\/p>\n\n\n\n<p><span><strong>III \u2013 DO DIREITO<\/strong><\/span><\/p>\n\n\n\n<p><span><strong>III.I \u2013 DA NULIDADE DO ATO JUR\u00cdDICO<\/strong><\/span><\/p>\n\n\n\n<p><span>A pretens\u00e3o da requerente est\u00e1 amplamente amparada pela legisla\u00e7\u00e3o p\u00e1tria, pela doutrina e jurisprud\u00eancia.<\/span><\/p>\n\n\n\n<p><span>Assim:<\/span><\/p>\n\n\n\n<p><span>C\u00f3digo Civil<\/span><span>: &#8220;Art.&nbsp;<\/span><span>524<\/span><span>. A lei assegura ao propriet\u00e1rio o direito de usar, gozar e dispor de seus bens, e de reav\u00ea-los do poder de quem quer que injustamente os possua.&#8221;<\/span><\/p>\n\n\n\n<p><span>&#8220;Examinando o enunciado do artigo 524 do diploma civil, vislumbra-se, sem esfor\u00e7o, que o direito de reaver o bem do qual foi despojado, \u00e9 elemento componente do direito de propriedade. Trata-se de defesa especial desse direito.&#8221;&nbsp;<\/span><span>[2]<\/span><\/p>\n\n\n\n<p><span>A a\u00e7\u00e3o de anula\u00e7\u00e3o de ato jur\u00eddico \u00e9 o rem\u00e9dio jur\u00eddico processual previsto pelo&nbsp;<\/span><span>C\u00f3digo Civil<\/span><span>:<\/span><\/p>\n\n\n\n<p><span>\u201cArt. 166. \u00c9 nulo o neg\u00f3cio jur\u00eddico quando:<\/span><\/p>\n\n\n\n<p><span>II \u2013 <\/span><span>for<\/span><span> il\u00edcito, imposs\u00edvel ou indetermin\u00e1vel o seu objeto;<\/span><\/p>\n\n\n\n<p><span>No caso houve dolo, tal seja, houve um artif\u00edcio elaborado de m\u00e1-f\u00e9 (fraude) assim h\u00e1 ilicitude quanto ao ato jur\u00eddico.<\/span><\/p>\n\n\n\n<p><span>O artigo,&nbsp;<\/span><span>123<\/span><span>&nbsp;do&nbsp;<\/span><span>C\u00f3digo Civil<\/span><span>&nbsp;assevera que:<\/span><\/p>\n\n\n\n<p><span>Invalidam os neg\u00f3cios jur\u00eddicos que lhe s\u00e3o subordinados:<\/span><\/p>\n\n\n\n<p><span>II- <\/span><span>as<\/span><span> condi\u00e7\u00f5es il\u00edcitas, ou de fazer coisa il\u00edcita;<\/span><\/p>\n\n\n\n<p><span>Al\u00e9m disso, o artigo&nbsp;<\/span><span>182<\/span><span>&nbsp;do&nbsp;<\/span><span>C\u00f3digo Civil<\/span><span>, ressalta que:<\/span><\/p>\n\n\n\n<p><span>Anulado o neg\u00f3cio jur\u00eddico, restituir-se-\u00e3o as partes ao estado em que antes dele se achavam, e, n\u00e3o sendo poss\u00edvel restitu\u00ed-las, ser\u00e3o indenizadas com o equivalente.<\/span><\/p>\n\n\n\n<p><span>Portanto, neste caso, o ato jur\u00eddico celebrado entre os procuradores, e a entrega de bem como objeto de garantia real, \u00e9 totalmente nulo de pleno direito.<\/span><\/p>\n\n\n\n<p><span>Eis que, n\u00e3o possibilidade de efetivar ato jur\u00eddico com ilicitude. Os procuradores agiram em totalmente discord\u00e2ncia com o ordenamento jur\u00eddico e causaram <\/span><span>dano<\/span><span> a requerente.<\/span><\/p>\n\n\n\n<p><span>Dessa forma, \u00e9 poss\u00edvel a nulidade desse ato. Retirando a hipoteca, at\u00e9 por que n\u00e3o h\u00e1 <\/span><span>vinculo<\/span><span> entre a requerente e __________. A requerente n\u00e3o pode responder por d\u00edvida que n\u00e3o \u00e9 sua, e tampouco, responder pelo seu bem que foi passado na escritura para outras pessoas sem sua autoriza\u00e7\u00e3o, e de seu marido.<\/span><\/p>\n\n\n\n<p><span>O cart\u00f3rio ressalta que o falecido marido da requerente foi at\u00e9 o cart\u00f3rio assinar, mas ele j\u00e1 tinha falecido, e \u00e9 isso que precisa ser explicado. Toda essa \u00e1rvore de ilicitude que est\u00e1 causando <\/span><span>dano<\/span><span> at\u00e9 hoje a requerente.<\/span><\/p>\n\n\n\n<p><span>Ainda sobre o assunto, o professor&nbsp;<\/span><span><strong>Paulo Nader&nbsp;<\/strong><\/span><span>nos ensina:<\/span><\/p>\n\n\n\n<p><span>\u201cO propriet\u00e1rio tem, ainda, o direito de reaver a coisa, podendo valer-se da a\u00e7\u00e3o reivindicat\u00f3ria, a fim de receber o que \u00e9 seu de quem injustamente o possua. Quando o dispositivo legal se refere a \u201cquem quer que injustamente a possua ou detenha\u201d,&nbsp;<\/span><span><strong>o legislador n\u00e3o restringe o poder \u00e0 posse injusta, que se caracteriza pela forma violenta, clandestina ou prec\u00e1ria de aquisi\u00e7\u00e3o. O voc\u00e1bulo \u201cinjustamente\u201d foi empregado em acep\u00e7\u00e3o bem ampla, como a\u00e7\u00e3o contr\u00e1ria ao valor justi\u00e7a ou pr\u00e1tica juridicamente conden\u00e1vel.&nbsp;<\/strong><\/span><span>A a\u00e7\u00e3o reivindicat\u00f3ria \u00e9 um&nbsp;<\/span><span><strong>pleito judicial formulado pelo propriet\u00e1rio, que n\u00e3o se encontra na posse da coisa, em face do n\u00e3o propriet\u00e1rio, que tem o objeto em seu poder sem uma raz\u00e3o jur\u00eddica.<\/strong><\/span><span>&nbsp;Parte leg\u00edtima para propor tal a\u00e7\u00e3o \u00e9 o propriet\u00e1rio e para figurar como r\u00e9u, o possuidor da coisa.\u201d (Curso de Direito Civil &#8211; Vol. 4 &#8211; Direito das Coisas, Ed. Forense &#8211; 2016).&nbsp;<\/span><span><strong>(grifos nossos).<\/strong><\/span><\/p>\n\n\n\n<p><span>Assim, o requerente prova o seu dom\u00ednio, oferecendo prova inconcussa da propriedade, com a respectiva transcri\u00e7\u00e3o e descrevendo o im\u00f3vel com suas confronta\u00e7\u00f5es, bem como demonstrar que a coisa reivindicada <\/span><span>encontra-se<\/span><span> na posse do requerido ________.<\/span><\/p>\n\n\n\n<p><span>Assim, o que se requer \u00e9 a imiss\u00e3o de posse para que a requerente possa pela primeira vez ocupar o im\u00f3vel, tendo em vista que \u00e9 propriet\u00e1ria, paga o IPTU em dia.<\/span><\/p>\n\n\n\n<p><span>Todos os documentos acostados aos autos corroboram com a tese autoral. Juntamos o Registro de Compra e Venda, Certid\u00e3o de \u00d4nus do Im\u00f3vel, Comprovantes de pagamento e quita\u00e7\u00e3o dos <\/span><span>IPTUs<\/span><span> relativos aos anos em que <\/span><span>adquiriu a propriedade, al\u00e9m de Boletim de Ocorr\u00eancia \u00e0 \u00e9poca dos fatos que demonstra que a posse exercida n\u00e3o \u00e9, jamais, pac\u00edfica.<\/span><\/p>\n\n\n\n<p><span>Com rela\u00e7\u00e3o \u00e0 documenta\u00e7\u00e3o pertencente a requerente, o&nbsp;<\/span><span>C\u00f3digo Civil<\/span><span>&nbsp;mais uma vez \u00e9 claro ao dizer que:<\/span><\/p>\n\n\n\n<p><span><strong>\u201c<\/strong><\/span><span><strong>Art<\/strong><\/span><span><strong>&nbsp;<\/strong><\/span><span>.<\/span><span>&nbsp;<\/span><span><strong>1.227<\/strong><\/span><span>. Os direitos reais sobre im\u00f3veis constitu\u00eddos, ou transmitidos por atos entre vivos, s\u00f3 se adquirem com o registro no Cart\u00f3rio de Registro de Im\u00f3veis dos referidos t\u00edtulos (<\/span><span><\/span><span><\/span><span><\/span><span>arts<\/span><span>. 1.245 a 1.247<\/span><span><\/span><span>), salvo os casos expressos neste C\u00f3digo.\u201d<\/span><\/p>\n\n\n\n<p><span>Assim:<\/span><\/p>\n\n\n\n<p><span>APELA\u00c7\u00c3O C\u00cdVEL EM A\u00c7\u00c3O REIVINDICAT\u00d3RIA. SENTEN\u00c7A QUE INDEFERIU O PEDIDO (ART.&nbsp;<\/span><span>267<\/span><span>, INCISO&nbsp;<\/span><span>I<\/span><span>,&nbsp;<\/span><span>CPC<\/span><span>\/73) E EXTINGUIU A A\u00c7\u00c3O. REQUISITOS DA A\u00c7\u00c3O REIVINDICAT\u00d3RIA S\u00c3O A ADEQUADA INDIVIDUALIZA\u00c7\u00c3O DA COISA E A PROVA DO DOM\u00cdNIO E DA POSSE INJUSTA POR OUTREM. STATUS DE PROPRIET\u00c1RIO DO IM\u00d3VEL N\u00c3O DEMONSTRADO. MERO RECIBO COM ASSINATURA ILEG\u00cdVEL. CONTA DE ENERGIA EL\u00c9TRICA. DOCUMENTOS N\u00c3O H\u00c1BEIS A COMPROVAR PROPRIEDADE DO IM\u00d3VEL. RECURSO DE APELA\u00c7\u00c3O CONHECIDO E DESPROVIDO. SENTEN\u00c7A MANTIDA.&nbsp;<\/span><span><strong>1. \u00c9 sabido que a a\u00e7\u00e3o reivindicat\u00f3ria \u00e9 aquela em que o propriet\u00e1rio n\u00e3o possuidor do bem busca sua retomada do possuidor n\u00e3o propriet\u00e1rio, disciplinada no art.&nbsp;<\/strong><\/span><span><strong>1.228<\/strong><\/span><span><strong>&nbsp;do&nbsp;<\/strong><\/span><span><strong>C\u00f3digo Civil<\/strong><\/span><span><strong>: &#8220;O propriet\u00e1rio tem a faculdade de usar, gozar e dispor da coisa, e o direito de reav\u00ea-la do poder de quem quer que injustamente a possua ou detenha&#8221;. 2. Os requisitos \u00e0 tutela possess\u00f3ria pela reivindicat\u00f3ria s\u00e3o a adequada individualiza\u00e7\u00e3o da coisa e a prova do dom\u00ednio e da posse injusta por outrem.<\/strong><\/span><span>&nbsp;3. Na hip\u00f3tese, contudo, os referidos pressupostos n\u00e3o foram integralmente satisfeitos, haja vista n\u00e3o haver prova da titularidade do dom\u00ednio do bem por parte dos apelantes, o que \u00e9 afer\u00edvel de pronto. 4. Os autores somente colacionaram um mero &#8220;recibo&#8221; que atesta a compra do terreno, com uma assinatura ileg\u00edvel do vendedor e sem firma reconhecida, n\u00e3o se prestando para atribuir a qualidade de propriet\u00e1rio do im\u00f3vel ao comprador. 5. Assim, o rem\u00e9dio jur\u00eddico eleito (a\u00e7\u00e3o reivindicat\u00f3ria) n\u00e3o se amolda \u00e0 pretens\u00e3o deduzida, pois os promoventes <\/span><span>possuem apenas um direito pessoal assegurado por um mero recibo que supostamente atesta a venda do im\u00f3vel ao de cujus e que sequer se pode verificar a pessoa do vendedor. 6.&nbsp;<\/span><span><strong>Ressalte-se que a demonstra\u00e7\u00e3o inequ\u00edvoca da propriedade \u00e9 requisito indispens\u00e1vel para a propositura de a\u00e7\u00e3o reivindicat\u00f3ria e, ausente este pressuposto essencial, deve ser decretada a falta de interesse processual, com a consequente extin\u00e7\u00e3o do processo.<\/strong><\/span><span>&nbsp;7. Recurso de Apela\u00e7\u00e3o conhecido e desprovido. Senten\u00e7a mantida. AC\u00d3RD\u00c3O Vistos, relatados e discutidos estes autos, acorda a Terceira C\u00e2mara de Direito Privado do Tribunal de Justi\u00e7a do Estado do Cear\u00e1, \u00e0 unanimidade, em CONHECER DO RECURSO DE APELA\u00c7\u00c3O, contudo para NEGAR-LHE PROVIMENTO, nos termos do voto da Relatora, que integra esta decis\u00e3o. DESA. MARIA VILAUBA FAUSTO LOPES RELATORA (TJ-CE &#8211; APL: 00057058520128060140 CE 0005705-85.2012.8.06.0140, Relator: MARIA VILAUBA FAUSTO LOPES, 3\u00aa C\u00e2mara Direito Privado, Data de Publica\u00e7\u00e3o: 28\/06\/2017<\/span><span><strong>) (grifos nossos)<\/strong><\/span><\/p>\n\n\n\n<p><span>APELA\u00c7\u00c3O C\u00cdVEL. PROPRIEDADE E DIREITOS REAIS SONRE COISAS ALHEIAS. A\u00c7\u00c3O REIVINDICAT\u00d3RIA. REIVINDICAT\u00d3RIA. REQUISITOS.&nbsp;<\/span><span><strong>A a\u00e7\u00e3o reivindicat\u00f3ria funda-se no direito de <\/strong><\/span><span><strong>seq\u00fcela<\/strong><\/span><span><strong> e requisita prova do dom\u00ednio do reivindicante, individualiza\u00e7\u00e3o do bem e posse injusta do r\u00e9u.<\/strong><\/span><span>&nbsp;&#8211; Circunst\u00e2ncia dos autos em que presente os requisitos se imp\u00f5e manter a proced\u00eancia da a\u00e7\u00e3o. RECURSO DESPROVIDO. (Apela\u00e7\u00e3o C\u00edvel N\u00ba 70074304189, D\u00e9cima Oitava C\u00e2mara C\u00edvel, Tribunal de Justi\u00e7a do RS, Relator: Jo\u00e3o Moreno Pomar, Julgado em 10\/08\/2017). (TJ-RS &#8211; AC: 70074304189 RS, Relator: Jo\u00e3o Moreno Pomar, Data de Julgamento: 10\/08\/2017, D\u00e9cima Oitava C\u00e2mara C\u00edvel, Data de Publica\u00e7\u00e3o: Di\u00e1rio da Justi\u00e7a do dia 17\/08\/2017)&nbsp;<\/span><span><strong>(grifos nossos)<\/strong><\/span><\/p>\n\n\n\n<p><span><strong>III.II- DA IMISS\u00c3O DE POSSE<\/strong><\/span><\/p>\n\n\n\n<p><span>A imiss\u00e3o de posse n\u00e3o est\u00e1 prevista <\/span><span>no<\/span><span> legisla\u00e7\u00e3o<\/span><span>, e n\u00e3o tem car\u00e1ter possess\u00f3rio. Entretanto, \u00e9 cab\u00edvel para aquele propriet\u00e1rio que nunca teve a posse. \u00c9 o que se requer.<\/span><\/p>\n\n\n\n<p><span>Apesar de sua peculiaridade, se assemelha as a\u00e7\u00f5es possess\u00f3rias, e muitos requisitos podem ser usados de forma extensiva por se tratar de propriedade, assim, direitos reais.<\/span><\/p>\n\n\n\n<p><span>No que tange a particularidades, a turba\u00e7\u00e3o ocorre desde que ______, estava dentro da propriedade e declarou a filha da requerente que iria fazer uma constru\u00e7\u00e3o l\u00e1 e que teria a escritura do im\u00f3vel que inclusive apresentou ao policial na data e hora que costa no boletim de ocorr\u00eancia.<\/span><\/p>\n\n\n\n<p><span>O esbulho \u00e9 h\u00e1 mais de 1 ano e de 1 dia, assim a presente a\u00e7\u00e3o \u00e9 de for\u00e7a velha, conforme artigo&nbsp;<\/span><span>558<\/span><span>,par\u00e1grafo \u00fanico, do&nbsp;<\/span><span>C\u00f3digo Civil<\/span><span>, que afirma que mesmo tendo passado 1 ano e 1 dia, n\u00e3o perder\u00e1 seu car\u00e1ter possess\u00f3rio.<\/span><\/p>\n\n\n\n<p><span>Quer se evitar que a turba\u00e7\u00e3o continue acontecendo a requerente.<\/span><\/p>\n\n\n\n<p><span><strong>III. III- PRINC\u00cdPIO DA FUNGIBILIDADE DAS A\u00c7\u00d5ES POSSESS\u00d3RIAS<\/strong><\/span><\/p>\n\n\n\n<p><span>Conforme assevera o artigo 554, do C\u00f3digo de Processo Civil:<\/span><\/p>\n\n\n\n<p><span><strong>A propositura de uma a\u00e7\u00e3o possess\u00f3ria em vez de outra <\/strong><\/span><span><strong>n<\/strong><\/span><span><strong>&nbsp;ao obstar\u00e1 a que o juiz conhe\u00e7a do pedido e outorgue a prote\u00e7\u00e3o legal correspondente \u00e0quele cujos pressupostos estejam provados.<\/strong><\/span><\/p>\n\n\n\n<p><span>Desse modo, se n\u00e3o for o entendimento de vossa excel\u00eancia pela imiss\u00e3o de posse, que seja entendido como qualquer a\u00e7\u00e3o possess\u00f3ria que seja a via mais adequada e assim eleita.<\/span><\/p>\n\n\n\n<p><span>Assim, o artigo 560 do C\u00f3digo de Processo Civil, afirma que \u201cO possuidor tem direito a ser mantido na posse em caso de turba\u00e7\u00e3o\u201d.<\/span><\/p>\n\n\n\n<p><span>J\u00e1 o artigo 561, elenca alguns requisitos que o autor deve provar, desse modo:<\/span><\/p>\n\n\n\n<p><span>I-&nbsp;<\/span><span><strong>SUA POSSE:<\/strong><\/span><span>&nbsp;A requerente possui a escritura e registro de im\u00f3vel, e da sua compra em 1977, que estar\u00e1 anexado.<\/span><\/p>\n\n\n\n<p><span>II-&nbsp;<\/span><span><strong>A TURBA\u00c7\u00c3O:<\/strong><\/span><span>&nbsp;Conforme boletim de ocorr\u00eancia, asseverando que SANDRO FERREIRA,<\/span><\/p>\n\n\n\n<p><span>III-&nbsp;<\/span><span><strong>A DATA DA TURBA\u00c7\u00c3O:<\/strong><\/span><span>&nbsp;A turba\u00e7\u00e3o come\u00e7ou quando ilicitamente SANDRO FERREIRA conseguiu a escritura do im\u00f3vel em seu nome, na propriedade come\u00e7ou a frequentar como se seu fosse. E mediante a data do Boletim de Ocorr\u00eancia \u00e9 poss\u00edvel verificar a turba\u00e7\u00e3o.<\/span><\/p>\n\n\n\n<p><span>IV-&nbsp;<\/span><span><strong>A CONTINUA\u00c7\u00c3O DA POSSE OU PERDA DA POSSE:<\/strong><\/span><span>&nbsp;Nunca houve a posse integral do bem, tampouco parcial.<\/span><\/p>\n\n\n\n<p><span>Desse modo, a perda da posse se deu assim que SANDRO FERREIRA adentrou na propriedade, e quando ARNALDO TRELINSKI hipotecou um bem que n\u00e3o \u00e9 seu atrav\u00e9s de procura\u00e7\u00e3o FALSA.<\/span><\/p>\n\n\n\n<p><span>Portanto, encontram-se todos os requisitos preenchidos e demonstrados a turba\u00e7\u00e3o para adquirir o direito \u00e0 imiss\u00e3o de posse.<\/span><\/p>\n\n\n\n<p><span><strong>III.IV- LIMINAR DE TUTELA ANTECIPADA<\/strong><\/span><\/p>\n\n\n\n<p><span>Assim, a <a href=\"https:\/\/advbox.com.br\/blog\/como-automatizar-seus-modelos-de-peticoes\/\" target=\"_blank\">peti\u00e7\u00e3o<\/a> encontra-se devidamente instru\u00edda, pois obt\u00e9m provas documentais quanto \u00e0 propriedade da requerente e a turba\u00e7\u00e3o feita pelos requeridos.<\/span><\/p>\n\n\n\n<p><span>E dessa forma, sem ouvir os requeridos requer a expedi\u00e7\u00e3o da liminar para coloca-los na posse a partir da imiss\u00e3o.<\/span><\/p>\n\n\n\n<p><span>A concess\u00e3o da antecipa\u00e7\u00e3o de tutela \u00e9 poss\u00edvel quando preenchidos os requisitos do art. 300 do C\u00f3digo de Processo Civil,&nbsp;<\/span><span>in <\/span><span>verbis<\/span><span>:<\/span><\/p>\n\n\n\n<p><span>\u201c<\/span><span>A tutela de urg\u00eancia ser\u00e1 concedida quando houver elementos que evidenciem a probabilidade do direito e o perigo de dano ou o risco ao resultado \u00fatil do processo.\u201d<\/span><\/p>\n\n\n\n<p><span>In <\/span><span>casu<\/span><span>, a requerente \u00e9 leg\u00edtima propriet\u00e1ria do terreno urbano injustamente ocupado pelo requerido, conforme se constata atrav\u00e9s da escritura p\u00fablica transcrita no cart\u00f3rio de registro de Im\u00f3veis desta Capital (PARAN\u00c1), sob o n\u00ba 4.534 de matr\u00edcula, documento este que acompanha a presente&nbsp;<\/span><span>actio<\/span><span>.<\/span><\/p>\n\n\n\n<p><span>Al\u00e9m disso, \u00e9 oportuno salientar que a requerente est\u00e1 sendo privada de usar, dispor e gozar do terreno urbano do qual \u00e9 propriet\u00e1ria em virtude da posse e propriedade injusta dos requeridos, vislumbra-se, assim, o fundado receio de dano irrepar\u00e1vel a mesma.<\/span><\/p>\n\n\n\n<p><span>Assim, o artigo 300, do C\u00f3digo de Processo Civil, estabeleceu que o magistrado pudesse conceder a antecipa\u00e7\u00e3o dos efeitos da tutela pretendida no pedido inicial, a imiss\u00e3o da autora na posse do im\u00f3vel acima individualizado, quando presentes os requisitos de lei. Robusta a prova trazida aos autos, ou seja, o t\u00edtulo de dom\u00ednio, sendo ele pr\u00f3prio e legalmente constitu\u00eddo, oriundo de Escritura P\u00fablica de Compra e Venda, com as formalidades exigidas por lei, inclusive com o invent\u00e1rio do esp\u00f3lio.<\/span><\/p>\n\n\n\n<p><span>N\u00e3o h\u00e1 perigo de irreversibilidade da medida, eis que o direito da autora \u00e9 pretendido com provas documentais e testemunhais.<\/span><\/p>\n\n\n\n<p><span>Corroborando assim, para dizer que os requeridos nunca possu\u00edram direito <\/span><span>algum sobra<\/span><span> \u00e0quela propriedade e dessa forma, n\u00e3o ter\u00e3o nenhum tipo de dano, tendo em vista que agiram com dolo, e adquiriram um bem a partir de apropria\u00e7\u00e3o ind\u00e9bita.<\/span><\/p>\n\n\n\n<p><span>O perigo de dano est\u00e1 demonstrado a partir do documento que comprova sua aquisi\u00e7\u00e3o do bem, que pagou e que nunca pode ter a posse do bem por que os requeridos n\u00e3o a deixaram.<\/span><\/p>\n\n\n\n<p><span>A probabilidade do direito encontra-se nas provas documentais, onde consta a compra e venda, certid\u00f5es, registro de im\u00f3veis, IPTU e Boletim de Ocorr\u00eancia.<\/span><\/p>\n\n\n\n<p><span>Portanto, requer-se a tutela antecipada para o fim de que seja antecipado o m\u00e9rito no que tange a posse ser <\/span><span>concecida<\/span><span> desde logo.<\/span><\/p>\n\n\n\n<p><span><strong>VI \u2013 DO PEDIDO<\/strong><\/span><\/p>\n\n\n\n<p><span>Em face de todo o exposto, requer a Vossa Excel\u00eancia:<\/span><\/p>\n\n\n\n<p><span>a) A concess\u00e3o dos benef\u00edcios da assist\u00eancia judici\u00e1ria gratuita, tendo em vista que a requerente n\u00e3o possui recursos de arcar com as despesas do processo sem preju\u00edzo pr\u00f3prio e de sua fam\u00edlia nos termos da Lei&nbsp;<\/span><span>1060<\/span><span>\/50 e Artigo 98 do C\u00f3digo de Processo Civil;<\/span><\/p>\n\n\n\n<p><span>b) Tramita\u00e7\u00e3o Priorit\u00e1ria com fulcro no artigo&nbsp;<\/span><span>1.048<\/span><span>,&nbsp;<\/span><span>I<\/span><span>, do&nbsp;<\/span><span><\/span><span><\/span><span><\/span><span>Cpc<\/span><span><\/span><span>&nbsp;e Artigo&nbsp;<\/span><span>71<\/span><span>,&nbsp;<\/span><span>\u00a7 1\u00ba<\/span><span>do&nbsp;<\/span><span>Estatuto do Idoso<\/span><span>.<\/span><\/p>\n\n\n\n<p><span>c) A liminar de imiss\u00e3o de posse em favor da requerente, sem ouvir o r\u00e9u e <\/span><span>independete<\/span><span> de audi\u00eancia de justifica\u00e7\u00e3o, uma vez que est\u00e1 devidamente instru\u00edda a <a href=\"https:\/\/advbox.com.br\/blog\/como-automatizar-seus-modelos-de-peticoes\/\" target=\"_blank\">peti\u00e7\u00e3o<\/a> inicial, nos termos do artigo&nbsp;<\/span><span>562<\/span><span>,&nbsp;<\/span><span>CPC<\/span><span>;<\/span><\/p>\n\n\n\n<p><span>d) A cita\u00e7\u00e3o do r\u00e9u para, querendo, contestar a a\u00e7\u00e3o, no prazo de 15 dias, conforme artigo&nbsp;<\/span><span>564<\/span><span>,&nbsp;<\/span><span>CPC<\/span><span>;<\/span><\/p>\n\n\n\n<p><span>e) A aplica\u00e7\u00e3o do princ\u00edpio da fungibilidade das a\u00e7\u00f5es possess\u00f3rias, nos termos do artigo&nbsp;<\/span><span>554<\/span><span>,&nbsp;<\/span><span>CPC<\/span><span>;<\/span><\/p>\n\n\n\n<p><span>f) A proced\u00eancia da a\u00e7\u00e3o, com acolhimento do pedido, nos termos do artigo&nbsp;<\/span><span>487<\/span><span>,&nbsp;<\/span><span>I<\/span><span>,&nbsp;<\/span><span>CPC<\/span><span>, para o fim de confirmar a liminar de imiss\u00e3o de posse a favor da requerente e ainda condenar o r\u00e9u em perdas e danos no valor de R$ 20.000,00 (vinte mil reais) conforme artigo&nbsp;<\/span><span>555<\/span><span>,&nbsp;<\/span><span>CPC<\/span><\/p>\n\n\n\n<p><span>g) Imposi\u00e7\u00e3o de medida necess\u00e1ria e adequada para evitar a nova turba\u00e7\u00e3o e para cumprir-se a tutela provis\u00f3ria, nos termos do artigo&nbsp;<\/span><span>555<\/span><span>,&nbsp;<\/span><span>CPC<\/span><span>;<\/span><\/p>\n\n\n\n<p><span>h) Produ\u00e7\u00e3o de todas as provas em direito admitidas, em especial a prova documental e testemunhal, nos termos do artigo&nbsp;<\/span><span>319<\/span><span>,&nbsp;<\/span><span>VI<\/span><span>&nbsp;do&nbsp;<\/span><span>CPC<\/span><span>;<\/span><\/p>\n\n\n\n<p><span>i) A juntada da guia de pagamento das custas e despesas de ingresso, nos termos do artigo&nbsp;<\/span><span>290<\/span><span>,&nbsp;<\/span><span>CPC<\/span><span>;<\/span><\/p>\n\n\n\n<p><span>j) A condena\u00e7\u00e3o do r\u00e9u ao pagamento das custas processuais e honor\u00e1rios advocat\u00edcios, conforme artigo&nbsp;<\/span><span>82<\/span><span>,&nbsp;<\/span><span>par\u00e1grafo 2<\/span><span>, artigo 84 e&nbsp;<\/span><span>85<\/span><span>,&nbsp;<\/span><span>CPC<\/span><span>.<\/span><\/p>\n\n\n\n<p><span><strong>D\u00e1-se a causa o valor de R$ 178.800,00 (cento e <\/strong><\/span><span><strong>setenta<\/strong><\/span><span><strong> e oito mil e oitocentos reais).<\/strong><\/span><\/p>\n\n\n\n<p><span>Nestes termos, <\/span><\/p>\n\n\n\n<p><span>pede e espera deferimento.<\/span><\/p>\n\n\n\n<p><span>&#8230; (Munic\u00edpio \u2013 UF), &#8230; (dia) de &#8230; (m\u00eas) de &#8230; (ano).<\/span><\/p>\n\n\n\n<p class=\"has-text-align-center\"><span><strong>ADVOGADO<\/strong><\/span><\/p>\n\n\n\n<p class=\"has-text-align-center\"><span>OAB n\u00b0 &#8230;. \u2013 UF<\/span><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/advbox.com.br\/blog\/como-automatizar-seus-modelos-de-peticoes\/\" target=\"_blank\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"270\" src=\"https:\/\/advbox.com.br\/blog\/wp-content\/uploads\/2025\/12\/CTA-REBRANDING-16.webp\" alt=\"Banner com imagem ilustrativa de automa\u00e7\u00e3o de peti\u00e7\u00f5es jur\u00eddicas, destacando cria\u00e7\u00e3o, padroniza\u00e7\u00e3o e controle de peti\u00e7\u00f5es para advogados com a ADVBOX\" class=\"wp-image-79759\" srcset=\"https:\/\/advbox.com.br\/blog\/wp-content\/uploads\/2025\/12\/CTA-REBRANDING-16.webp 1024w, https:\/\/advbox.com.br\/blog\/wp-content\/uploads\/2025\/12\/CTA-REBRANDING-16-500x132.webp 500w, https:\/\/advbox.com.br\/blog\/wp-content\/uploads\/2025\/12\/CTA-REBRANDING-16-768x203.webp 768w, https:\/\/advbox.com.br\/blog\/wp-content\/uploads\/2025\/12\/CTA-REBRANDING-16-150x40.webp 150w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>MODELO DE A\u00c7\u00c3O DE NULIDADE DE ATO JUR\u00cdDICO EXCELENT\u00cdSSIMO SENHOR DOUTOR JUIZ DE DIREITO DA VARA C\u00cdVEL DO FORO CENTRAL DA COMARCA DA REGI\u00c3O METROPOLITANA DE &#8230; &#8230; (nome completo em negrito da parte), &#8230; (nacionalidade), &#8230; (estado civil), &#8230; (profiss\u00e3o), portador do CPF\/MF n\u00ba &#8230;, com Documento de Identidade [&hellip;]<\/p>\n","protected":false},"author":44,"featured_media":79776,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"footnotes":""},"modelo_category":[1457,1481],"class_list":["post-11934","modelos","type-modelos","status-publish","has-post-thumbnail","hentry","modelo_category-direito","modelo_category-direito-civil"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Modelo de a\u00e7\u00e3o de nulidade de ato jur\u00eddico<\/title>\n<meta name=\"description\" content=\"Copie aqui sem restri\u00e7\u00f5es e baixe em word seu modelo de A\u00c7\u00c3O DE NULIDADE DE ATO JUR\u00cdDICO\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/advbox.com.br\/blog\/modelos\/acao-de-nulidade-de-ato-juridico\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Modelo de a\u00e7\u00e3o de nulidade de ato jur\u00eddico\" \/>\n<meta property=\"og:description\" content=\"Copie aqui sem restri\u00e7\u00f5es e baixe em word seu modelo de A\u00c7\u00c3O DE NULIDADE DE ATO JUR\u00cdDICO\" \/>\n<meta property=\"og:url\" content=\"https:\/\/advbox.com.br\/blog\/modelos\/acao-de-nulidade-de-ato-juridico\/\" \/>\n<meta property=\"og:site_name\" content=\"Software Jur\u00eddico Completo - ADVBOX\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/advbox\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-24T13:03:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/advbox.com.br\/blog\/wp-content\/uploads\/2025\/12\/sobrestamento-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@advbox2\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/advbox.com.br\/blog\/modelos\/acao-de-nulidade-de-ato-juridico\/\",\"url\":\"https:\/\/advbox.com.br\/blog\/modelos\/acao-de-nulidade-de-ato-juridico\/\",\"name\":\"Modelo de a\u00e7\u00e3o de nulidade de ato jur\u00eddico\",\"isPartOf\":{\"@id\":\"https:\/\/advbox.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/advbox.com.br\/blog\/modelos\/acao-de-nulidade-de-ato-juridico\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/advbox.com.br\/blog\/modelos\/acao-de-nulidade-de-ato-juridico\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/advbox.com.br\/blog\/wp-content\/uploads\/2025\/12\/sobrestamento-1.jpg\",\"datePublished\":\"2019-03-07T21:26:24+00:00\",\"dateModified\":\"2025-12-24T13:03:17+00:00\",\"description\":\"Copie aqui sem restri\u00e7\u00f5es e baixe em word seu modelo de A\u00c7\u00c3O DE NULIDADE DE ATO JUR\u00cdDICO\",\"breadcrumb\":{\"@id\":\"https:\/\/advbox.com.br\/blog\/modelos\/acao-de-nulidade-de-ato-juridico\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/advbox.com.br\/blog\/modelos\/acao-de-nulidade-de-ato-juridico\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/advbox.com.br\/blog\/modelos\/acao-de-nulidade-de-ato-juridico\/#primaryimage\",\"url\":\"https:\/\/advbox.com.br\/blog\/wp-content\/uploads\/2025\/12\/sobrestamento-1.jpg\",\"contentUrl\":\"https:\/\/advbox.com.br\/blog\/wp-content\/uploads\/2025\/12\/sobrestamento-1.jpg\",\"width\":1024,\"height\":576,\"caption\":\"Banner institucional da ADVBOX com elemento visual abstrato em tons de azul, representando estrutura, tecnologia e identidade visual da marca\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/advbox.com.br\/blog\/modelos\/acao-de-nulidade-de-ato-juridico\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/advbox.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Modelos\",\"item\":\"https:\/\/advbox.com.br\/blog\/modelos\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Modelo de a\u00e7\u00e3o de nulidade de ato jur\u00eddico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/advbox.com.br\/blog\/#website\",\"url\":\"https:\/\/advbox.com.br\/blog\/\",\"name\":\"Software Jur\u00eddico Completo - ADVBOX\",\"description\":\"Plataforma para Advocacia Digital\",\"publisher\":{\"@id\":\"https:\/\/advbox.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/advbox.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/advbox.com.br\/blog\/#organization\",\"name\":\"ADVBOX Blog - Software jur\u00eddico da advocacia digital\",\"url\":\"https:\/\/advbox.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/advbox.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/advbox.com.br\/blog\/wp-content\/uploads\/2019\/12\/Como-aumentar-a-produtividade_.jpg\",\"contentUrl\":\"https:\/\/advbox.com.br\/blog\/wp-content\/uploads\/2019\/12\/Como-aumentar-a-produtividade_.jpg\",\"width\":320,\"height\":213,\"caption\":\"ADVBOX Blog - Software jur\u00eddico da advocacia digital\"},\"image\":{\"@id\":\"https:\/\/advbox.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/advbox\/\",\"https:\/\/x.com\/advbox2\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Modelo de a\u00e7\u00e3o de nulidade de ato jur\u00eddico","description":"Copie aqui sem restri\u00e7\u00f5es e baixe em word seu modelo de A\u00c7\u00c3O DE NULIDADE DE ATO JUR\u00cdDICO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/advbox.com.br\/blog\/modelos\/acao-de-nulidade-de-ato-juridico\/","og_locale":"pt_BR","og_type":"article","og_title":"Modelo de a\u00e7\u00e3o de nulidade de ato jur\u00eddico","og_description":"Copie aqui sem restri\u00e7\u00f5es e baixe em word seu modelo de A\u00c7\u00c3O DE NULIDADE DE ATO JUR\u00cdDICO","og_url":"https:\/\/advbox.com.br\/blog\/modelos\/acao-de-nulidade-de-ato-juridico\/","og_site_name":"Software Jur\u00eddico Completo - ADVBOX","article_publisher":"https:\/\/www.facebook.com\/advbox\/","article_modified_time":"2025-12-24T13:03:17+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/advbox.com.br\/blog\/wp-content\/uploads\/2025\/12\/sobrestamento-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@advbox2","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/advbox.com.br\/blog\/modelos\/acao-de-nulidade-de-ato-juridico\/","url":"https:\/\/advbox.com.br\/blog\/modelos\/acao-de-nulidade-de-ato-juridico\/","name":"Modelo de a\u00e7\u00e3o de nulidade de ato jur\u00eddico","isPartOf":{"@id":"https:\/\/advbox.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/advbox.com.br\/blog\/modelos\/acao-de-nulidade-de-ato-juridico\/#primaryimage"},"image":{"@id":"https:\/\/advbox.com.br\/blog\/modelos\/acao-de-nulidade-de-ato-juridico\/#primaryimage"},"thumbnailUrl":"https:\/\/advbox.com.br\/blog\/wp-content\/uploads\/2025\/12\/sobrestamento-1.jpg","datePublished":"2019-03-07T21:26:24+00:00","dateModified":"2025-12-24T13:03:17+00:00","description":"Copie aqui sem restri\u00e7\u00f5es e baixe em word seu modelo de A\u00c7\u00c3O DE NULIDADE DE ATO JUR\u00cdDICO","breadcrumb":{"@id":"https:\/\/advbox.com.br\/blog\/modelos\/acao-de-nulidade-de-ato-juridico\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/advbox.com.br\/blog\/modelos\/acao-de-nulidade-de-ato-juridico\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/advbox.com.br\/blog\/modelos\/acao-de-nulidade-de-ato-juridico\/#primaryimage","url":"https:\/\/advbox.com.br\/blog\/wp-content\/uploads\/2025\/12\/sobrestamento-1.jpg","contentUrl":"https:\/\/advbox.com.br\/blog\/wp-content\/uploads\/2025\/12\/sobrestamento-1.jpg","width":1024,"height":576,"caption":"Banner institucional da ADVBOX com elemento visual abstrato em tons de azul, representando estrutura, tecnologia e identidade visual da marca"},{"@type":"BreadcrumbList","@id":"https:\/\/advbox.com.br\/blog\/modelos\/acao-de-nulidade-de-ato-juridico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/advbox.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Modelos","item":"https:\/\/advbox.com.br\/blog\/modelos\/"},{"@type":"ListItem","position":3,"name":"Modelo de a\u00e7\u00e3o de nulidade de ato jur\u00eddico"}]},{"@type":"WebSite","@id":"https:\/\/advbox.com.br\/blog\/#website","url":"https:\/\/advbox.com.br\/blog\/","name":"Software Jur\u00eddico Completo - ADVBOX","description":"Plataforma para Advocacia Digital","publisher":{"@id":"https:\/\/advbox.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/advbox.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/advbox.com.br\/blog\/#organization","name":"ADVBOX Blog - Software jur\u00eddico da advocacia digital","url":"https:\/\/advbox.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/advbox.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/advbox.com.br\/blog\/wp-content\/uploads\/2019\/12\/Como-aumentar-a-produtividade_.jpg","contentUrl":"https:\/\/advbox.com.br\/blog\/wp-content\/uploads\/2019\/12\/Como-aumentar-a-produtividade_.jpg","width":320,"height":213,"caption":"ADVBOX Blog - Software jur\u00eddico da advocacia digital"},"image":{"@id":"https:\/\/advbox.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/advbox\/","https:\/\/x.com\/advbox2"]}]}},"_links":{"self":[{"href":"https:\/\/advbox.com.br\/blog\/wp-json\/wp\/v2\/modelos\/11934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/advbox.com.br\/blog\/wp-json\/wp\/v2\/modelos"}],"about":[{"href":"https:\/\/advbox.com.br\/blog\/wp-json\/wp\/v2\/types\/modelos"}],"author":[{"embeddable":true,"href":"https:\/\/advbox.com.br\/blog\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/advbox.com.br\/blog\/wp-json\/wp\/v2\/comments?post=11934"}],"version-history":[{"count":5,"href":"https:\/\/advbox.com.br\/blog\/wp-json\/wp\/v2\/modelos\/11934\/revisions"}],"predecessor-version":[{"id":80162,"href":"https:\/\/advbox.com.br\/blog\/wp-json\/wp\/v2\/modelos\/11934\/revisions\/80162"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/advbox.com.br\/blog\/wp-json\/wp\/v2\/media\/79776"}],"wp:attachment":[{"href":"https:\/\/advbox.com.br\/blog\/wp-json\/wp\/v2\/media?parent=11934"}],"wp:term":[{"taxonomy":"modelo_category","embeddable":true,"href":"https:\/\/advbox.com.br\/blog\/wp-json\/wp\/v2\/modelo_category?post=11934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}