{"id":12423,"date":"2019-03-07T18:21:59","date_gmt":"2019-03-07T18:21:59","guid":{"rendered":"https:\/\/advbox.com.br\/blog\/?post_type=modelos&#038;p=12423"},"modified":"2025-05-07T15:23:49","modified_gmt":"2025-05-07T18:23:49","slug":"obrigacao-de-fazer","status":"publish","type":"modelos","link":"https:\/\/advbox.com.br\/blog\/modelos\/obrigacao-de-fazer\/","title":{"rendered":"Modelo de a\u00e7\u00e3o de obriga\u00e7\u00e3o de fazer e inexist\u00eancia de d\u00e9bito (CRLV\/IPVA)"},"content":{"rendered":"<p style=\"text-align: center; background: #eee; padding: 10px;\"><strong><em>Quer descobrir como automatizar o preenchimento de todos os seus modelos de peti\u00e7\u00e3o e otimizar o tempo de toda sua equipe? <a href=\"https:\/\/advbox.com.br\/blog\/como-automatizar-seus-modelos-de-peticoes\/\" alt=\"Automatize o preenchimento das suas Peti\u00e7\u00f5es e otimize Tempo\" target=\"_blank\">Clique aqui<\/a><\/em><\/strong><\/p>\n<h1><strong>MODELO DE OBRIGA\u00c7\u00c3O DE FAZER<\/strong><\/h1>\n<p style=\"text-align: justify;\"><span><strong>EXCE<\/strong><\/span><span><strong>LENT\u00cdSSIMO SENHOR DOUTOR JUIZ DE<\/strong><\/span><span><strong> <\/strong><\/span><span><strong>DIREITO<\/strong><\/span><span><strong> DA <\/strong><\/span><span><strong>&#8230; <\/strong><\/span><span><strong>\u00aa VARA <\/strong><\/span><span><strong>C\u00cdVEL (JUIZADO ESPECIAL)<\/strong><\/span><span><strong> DA COMARCA DE <\/strong><\/span><span><strong>CIDADE<\/strong><\/span><span><strong>&#8211;<\/strong><\/span><span><strong>ESTADO<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span><strong>&#8230; <\/strong><\/span><span><strong>(nome completo em negrito da parte)<\/strong><\/span><span>, <\/span><span>&#8230; (nacionalidade)<\/span><span>, <\/span><span>&#8230; (estado civil)<\/span><span>, <\/span><span>&#8230; (profiss\u00e3o)<\/span><span>, portador <\/span><span>do<\/span><span> CPF\/MF n\u00ba <\/span><span>&#8230;, com Documento de Identidade de n\u00b0 &#8230;, residente e domiciliado na <\/span><span>Rua &#8230;, n. &#8230;, &#8230; (bairro), CE<\/span><span>P: &#8230;, &#8230; (Munic\u00edpio \u2013 UF)<\/span><span>, <\/span><span>vem respeitosamente perante a Vossa Excel\u00eancia propor:<\/span><\/p>\n<p style=\"text-align: center;\"><span><strong>A\u00c7\u00c3O DE OBRIGA\u00c7\u00c3O DE FAZER COM PEDIDO DE ANTECIPA\u00c7\u00c3O DE TUTELA E DECLARA\u00c7\u00c3O DE INEXIST\u00caNCIA DE D\u00c9BITO<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span>em face <\/span><span>de <\/span><span><strong>&#8230; (nome em negrito da parte)<\/strong><\/span><span>, <\/span><span>&#8230; (indicar se \u00e9 pessoa f\u00edsica ou jur\u00eddica), com CPF\/CNPJ de n. &#8230;, com sede na <\/span><span>Rua &#8230;, n. &#8230;, &#8230; (bairro), CEP: &#8230;, &#8230; (<\/span><span>Munic\u00edpio<\/span><span>\u2013 UF)<\/span><span>, pelas raz\u00f5es de fato e de direito que passa a aduzir e no final requer.:<\/span><\/p>\n<p style=\"text-align: justify;\"><span><strong>DA GRATUIDADE DA JUSTI\u00c7A<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span>Preliminarmente, afirma, sob as penas da Lei, ser pessoa economicamente hipossuficiente, n\u00e3o dispondo de recursos suficientes para arcar com as custas e demais despesas processuais sem preju\u00edzo de seu sustento e de sua fam\u00edlia.<\/span><\/p>\n<p style=\"text-align: justify;\"><span>Por tais raz\u00f5es, pleiteia-se os <\/span><span><\/span><span><\/span><span><\/span><span>benef\u00edcios<\/span><span><\/span><span> da Justi\u00e7a Gratuita, assegurados pela <\/span><span>Constitui\u00e7\u00e3o Federal<\/span><span>, artigo <\/span><span>5\u00ba<\/span><span>, <\/span><span>LXXIV<\/span><span> e pela Lei <\/span><span>13.105<\/span><span>\/2015 (<\/span><span>CPC<\/span><span>), artigo <\/span><span>98<\/span><span> e seguintes <\/span><\/p>\n<p style=\"text-align: justify;\"><span><strong>DOS FATOS<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span>O Requerente firmou com a empresa Cons\u00f3rcio Nacional HONDA, em 16\/03\/2015, um contrato visando a aquisi\u00e7\u00e3o de uma motocicleta modelo NXR160 BROS ESDD, nova, conforme documento anexo, e para tanto investiu na condi\u00e7\u00e3o de consorciado, de plano cujo sistema se denomina &#8220;Cons\u00f3rcio&#8221; <\/span><span>sistema este que se destina a aquisi\u00e7\u00e3o de bens atrav\u00e9s de poupan\u00e7a popular com a capta\u00e7\u00e3o antecipada. <\/span><\/p>\n<p style=\"text-align: justify; margin-left: 40px;\"><span>Em 15\/05\/2016 o Autor foi contemplado e foi buscar a moto desejada, logo, sabendo de suas responsabilidades procurou o DETRAN\/MT para realizar todas as burocracias necess\u00e1rias a um ve\u00edculo novo, ent\u00e3o fez o primeiro emplacamento, conforme foto acostada aos autos, pagou o seguro e licenciamento do ve\u00edculo e ficou na espera do documento Certificado de Registro de Licenciamento do Ve\u00edculo (CRLV), em sua resid\u00eancia, conforme orienta\u00e7\u00e3o do funcion\u00e1rio do \u00f3rg\u00e3o r\u00e9u.<\/span><\/p>\n<p style=\"text-align: justify;\"><span>Ap\u00f3s 35 dias, o Requerente nada recebeu em sua resid\u00eancia, ent\u00e3o procurou novamente o DETRAN\/MT, em 05\/07\/2016, e foi informado que deveria pagar o IPVA\/2016.<\/span><\/p>\n<p style=\"text-align: justify;\"><span>Sabendo que tem direito a isen\u00e7\u00e3o, o Autor esclareceu que o ve\u00edculo \u00e9 novo e adquirido em 2016 e o funcion\u00e1rio do DETRAN\/MT reconheceu tal direito dizendo que mandaria um <\/span><span>email<\/span><span> ao setor respons\u00e1vel e que retornasse depois de 05 (cinco) dias.<\/span><\/p>\n<p style=\"text-align: justify;\"><span>Em 12\/07\/2016, o Requerente retornou \u00e0 ag\u00eancia do DETRAN e foi informado que ainda n\u00e3o tinham resposta e pediram mais 03 (tr\u00eas) dias. O Autor retornou no dia 15\/07\/2016 e a resposta foi a mesma.<\/span><\/p>\n<p style=\"text-align: justify;\"><span>Por fim, em 27\/07\/2016 o Requerente, mais uma vez, se dirigiu ao \u00f3rg\u00e3o r\u00e9u na expectativa de ter seu problema solucionado e documenta\u00e7\u00e3o expedida, contudo, nada ocorreu, apenas um <\/span><span>email<\/span><span> foi enviado, no dia 12\/07\/2016, sem SEQUER explicar a situa\u00e7\u00e3o e o setor respons\u00e1vel at\u00e9 hoje n\u00e3o enviou nenhuma resposta. <\/span><\/p>\n<p style=\"text-align: justify;\"><span>Diante do fato, observando-se a urg\u00eancia em que o Autor possui para utilizar a motocicleta para ir para a faculdade, est\u00e1gio e fazer suas atividades di\u00e1rias, e devido protela\u00e7\u00e3o da Autarquia R\u00e9 em expedir e fornecer o documento necess\u00e1rio para tanto, nada mais resta sen\u00e3o buscar seu direito atrav\u00e9s das vias judiciais.<\/span><\/p>\n<p style=\"text-align: justify;\"><span><strong>DO DIREITO<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span>A n\u00e3o expedi\u00e7\u00e3o do documento do ve\u00edculo do Autor configura-se conduta abusiva cometida pela R\u00e9, pois sem a CRLV o Autor fica impossibilitado de pilotar sua motocicleta, ou seja, foi comprada para ficar na garagem. Desse modo \u00e9 necess\u00e1ria a imediata expedi\u00e7\u00e3o do documento e decretada a <\/span><span>inexist\u00eancia do d\u00e9bito, uma vez que o ve\u00edculo \u00e9 novo e faz jus a isen\u00e7\u00e3o do IPVA. <\/span><\/p>\n<p style=\"text-align: justify;\"><span>Quanto a posterga\u00e7\u00e3o do DETRAN\/MT em expedir o documento, \u00e9 cedi\u00e7o lembrar que o mesmo \u00e9 de obriga\u00e7\u00e3o do \u00f3rg\u00e3o r\u00e9u, assegurado a todos e consagrado no art. <\/span><span>22<\/span><span> do <\/span><span>C\u00f3digo de Tr\u00e2nsito Brasileiro<\/span><span>, sen\u00e3o vejamos:<\/span><\/p>\n<p style=\"text-align: justify; margin-left: 120px;\"><span>Art. 22. Compete aos \u00f3rg\u00e3os ou entidades executivos de tr\u00e2nsito dos Estados e do Distrito Federal, no \u00e2mbito de sua circunscri\u00e7\u00e3o: III &#8211; vistoriar, inspecionar quanto \u00e0s condi\u00e7\u00f5es de seguran\u00e7a veicular, registrar, emplacar, selar a placa, e licenciar ve\u00edculos, <\/span><span><strong>expedindo o Certificado de Registro e o Licenciamento Anual<\/strong><\/span><span>, mediante delega\u00e7\u00e3o do \u00f3rg\u00e3o federal competente; <\/span><\/p>\n<p style=\"text-align: center;\"><span>[&#8230;]<\/span><\/p>\n<p style=\"text-align: justify; margin-left: 120px;\"><span>No que tange ao IPVA cobrado, salienta-se, que a cobran\u00e7a \u00e9 indevida, vez que a Lei estadual n\u00ba 8.069\/2004 (<\/span><span><strong>verificar lei estadual de cada estado<\/strong><\/span><span>) disp\u00f5e que os ve\u00edculos novos ser\u00e3o isentos do referido imposto no primeiro ano, vejamos:<\/span><\/p>\n<p style=\"text-align: justify; margin-left: 120px;\"><span><strong>Art. 1\u00ba<\/strong><\/span><span> Fica o Poder Executivo autorizado a reduzir, em at\u00e9 100% (cem por cento), a base de c\u00e1lculo do Imposto sobre a Propriedade de Ve\u00edculos Automotores \u2013 IPVA, devido: I &#8211; na data da aquisi\u00e7\u00e3o interna de ve\u00edculo automotor terrestre novo, de que tratam os incisos I a III do art. 5\u00ba, nas hip\u00f3teses previstas nos incisos I a III do art. 3\u00ba, ambos da Lei n\u00ba 7.301, de 17 de julho de 2000; <\/span><\/p>\n<p style=\"text-align: center;\"><span><strong>[&#8230;]<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span>Assim, disp\u00f5e o art. 3\u00ba, I da lei <\/span><span>7.301<\/span><span>\/00:<\/span><\/p>\n<p style=\"text-align: justify; margin-left: 120px;\"><span>Art. 3\u00ba Ocorre o fato gerador do imposto: I &#8211; na data da primeira aquisi\u00e7\u00e3o do ve\u00edculo novo por consumidor final;<\/span><\/p>\n<p style=\"text-align: center;\"><span>[&#8230;]<\/span><\/p>\n<p style=\"text-align: justify;\"><span>Ademais, segue uma not\u00edcia que informa tal benef\u00edcio aos contribuintes:<\/span><\/p>\n<p style=\"text-align: justify; margin-left: 120px;\"><span>O Governo de Mato Grosso, por meio da Secretaria de Estado de Fazenda (<\/span><span>Sefaz<\/span><span>-MT), esclarece aos contribuintes sobre os crit\u00e9rios para se usufruir da isen\u00e7\u00e3o do Imposto Sobre a Propriedade de Ve\u00edculos Automotores (IPVA) no ano de aquisi\u00e7\u00e3o do ve\u00edculo. Importante destacar que o benef\u00edcio \u00e9 v\u00e1lido somente para o ano em que o ve\u00edculo \u00e9 adquirido, independente do m\u00eas. Nesse sentido, um carro comprado no m\u00eas de dezembro de 2011 ter\u00e1 a isen\u00e7\u00e3o somente para este m\u00eas (dezembro de 2011), ou seja, a partir de janeiro de 2012 um novo IPVA <\/span><span>\u00e9 gerado referente ao exerc\u00edcio de 2012 e deve ser recolhido normalmente pelo contribuinte. [&#8230;]<\/span><\/p>\n<p style=\"text-align: justify; margin-left: 120px;\"><span>Fonte: <span><\/span><span><\/span><span><\/span><span><\/span><span><\/span><span><\/span><span> > <\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span>Resta demonstrado, ent\u00e3o, que o Requerente possui isen\u00e7\u00e3o quanto ao IPVA do ano de 2016, ano de aquisi\u00e7\u00e3o do ve\u00edculo, e consequentemente, n\u00e3o possui d\u00e9bitos com o r\u00e9u.<\/span><\/p>\n<p style=\"text-align: justify;\"><span>Dessa forma, pede-se que seja declarada a inexist\u00eancia do d\u00e9bito e que seja o R\u00e9u intimado a expedir do documento da motocicleta do Autor.<\/span><\/p>\n<p style=\"text-align: justify;\"><span><strong>DA ANTECIPA\u00c7\u00c3O DE TUTELA<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span>H\u00e1 necessidade da antecipa\u00e7\u00e3o de tutela para evitar que haja dano material e at\u00e9 les\u00e3o \u00e0 direito da personalidade do autor se perpetue e que os danos se prolonguem no tempo.<\/span><\/p>\n<p style=\"text-align: justify;\"><span>O<\/span><span> periculum in mora<\/span><span> est\u00e1 caracterizado, pois, o Autor necessita do documento anual do ve\u00edculo, qual seja, Certificado de Registro e Licenciamento do Ve\u00edculo (CRLV) para ir \u00e0 faculdade e est\u00e1gio, al\u00e9m de obriga\u00e7\u00f5es rotineiras, e n\u00e3o pode utilizar seu pr\u00f3prio ve\u00edculo, pois, se arrisca a ser parado em alguma <\/span><span>blitz<\/span><span>, ter sua moto apreendida e sofrer danos materiais, vez que, a les\u00e3o patrimonial se consumar\u00e1. <\/span><\/p>\n<p style=\"text-align: justify;\"><span>Logo, tal situa\u00e7\u00e3o justifica o pedido de liminar pleiteado. Assim, o diferimento da pretens\u00e3o preambular poder\u00e1 acrescer mais danos aos que est\u00e3o sendo suportados atualmente pelo requerente.<\/span><\/p>\n<p style=\"text-align: justify;\"><span>Incontest\u00e1vel, ainda, a absoluta reversibilidade da medida que se pede. Acaso no decorrer da lide se mostrem relevantes motivos jur\u00eddicos em contraposi\u00e7\u00e3o aos agora apresentados, a quest\u00e3o poder\u00e1 ser revista ou modificada segundo entendimento do Juiz.<\/span><\/p>\n<p style=\"text-align: justify;\"><span>Quanto ao <\/span><span>fumus boni juris<\/span><span>, presente se faz, evidente razoabilidade das alega\u00e7\u00f5es do promovente, bem como prova material robusta e apta ao acolhimento da tutela pretendida.<\/span><\/p>\n<p style=\"text-align: justify;\"><span>As provas inequ\u00edvocas, capazes de convencer esse Ju\u00edzo da verossimilhan\u00e7a dos fatos aqui alegados est\u00e3o tamb\u00e9m presentes, conforme farta documenta\u00e7\u00e3o acostada aos autos.<\/span><\/p>\n<p style=\"text-align: justify;\"><span>Destarte, a verossimilhan\u00e7a da alega\u00e7\u00e3o, ao lado da prova inequ\u00edvoca do direito buscado pelo requerente e do seu receio de dano maior e irrepar\u00e1vel ao patrim\u00f4nio familiar, trazem a esta querela o cumprimento integral da reda\u00e7\u00e3o prevista no artigo <\/span><span>294<\/span><span>, par\u00e1grafo \u00fanico, do <\/span><span>C\u00f3digo de Processo Civil<\/span><span>.<\/span><\/p>\n<p style=\"text-align: justify;\"><span>A antecipa\u00e7\u00e3o da tutela, portanto, tem como maior finalidade amparar o requerente at\u00e9 o julgamento definitivo, evitando-lhe danos futuros. Logo, na conformidade da reda\u00e7\u00e3o legal, o requerente faz jus \u00e0 concess\u00e3o da tutela antecipat\u00f3ria, uma vez que preenche todos os requisitos por ela exigidos: prova inequ\u00edvoca dos fatos e dano irrepar\u00e1vel.<\/span><\/p>\n<p style=\"text-align: justify;\"><span>Por isto, estando presentes os requisitos autorizadores da liminar, requer sua concess\u00e3o para que o DETRAN\/MT libere o sistema e realize a confec\u00e7\u00e3o do documento do ve\u00edculo.<\/span><\/p>\n<p style=\"text-align: justify;\"><span><strong>DOS PEDIDOS<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span><strong><\/strong><\/span><span>Por todo exposto, requer:<\/span><\/p>\n<p style=\"text-align: justify; margin-left: 120px;\"><span>I \u2013 REQUER CONCESS\u00c3O DE TUTELA ANTECIPADA para determinar que o DETRAN\/MT confeccione e entregue o documento da motocicleta ao Autor;<\/span><\/p>\n<p style=\"text-align: justify; margin-left: 120px;\"><span>II \u2013 Que seja citado o DETRAN\/MT, na pessoa do seu representante, a fim de responder aos termos da presente demanda;<\/span><\/p>\n<p style=\"text-align: justify; margin-left: 120px;\"><span>III \u2013 Que seja julgado totalmente procedente o pedido, a resultar na CONDENA\u00c7\u00c3O definitiva do DETRAN\/MT ao cumprimento de <\/span><span>OBRIGA\u00c7\u00c3O DE FAZER<\/span><span>, na esp\u00e9cie, consistente na confec\u00e7\u00e3o e fornecimento da documenta\u00e7\u00e3o necess\u00e1ria para o Autor transitar pela cidade com sua motocicleta e declara\u00e7\u00e3o de inexist\u00eancia do d\u00e9bito; <\/span><\/p>\n<p style=\"text-align: justify; margin-left: 120px;\"><span>IV &#8211; Requer digne-se Vossa Excel\u00eancia de, recebendo a presente <a href=\"https:\/\/advbox.com.br\/blog\/como-automatizar-seus-modelos-de-peticoes\/\" target=\"_blank\">peti\u00e7\u00e3o<\/a> inicial e conforme declara\u00e7\u00e3o anexa que a instrui, deferir o pedido de JUSTI\u00c7A GRATUITA.<\/span><\/p>\n<p style=\"text-align: justify; margin-left: 120px;\"><span>VI<\/span><span><strong> \u2013<\/strong><\/span><span> D\u00e1-se ao valor da causa R$ 1.000,00 (hum mil reais).<\/span><\/p>\n<p style=\"text-align: justify;\"><span>Nestes termos, <\/span><\/p>\n<p style=\"text-align: justify;\"><span>pede e espera deferimento.<\/span><\/p>\n<p style=\"text-align: justify;\"><span>&#8230; (Munic\u00edpio \u2013 UF), &#8230; (dia) de &#8230; (m\u00eas) de &#8230; (ano).<\/span><\/p>\n<p style=\"text-align: center; margin-left: 80px;\"><span><strong>ADVOGADO<\/strong><\/span><\/p>\n<p style=\"text-align: center; margin-left: 80px;\"><span>OAB n\u00b0 &#8230;. &#8211; UF<\/span><\/p>\n<p style=\"text-align: center; margin-left: 0px;\">\n<p style=\"text-align: center;\"><a href=\"https:\/\/advbox.com.br\/blog\/como-automatizar-seus-modelos-de-peticoes\/\" target=\"_blank\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/advbox.com.br\/blog\/wp-content\/uploads\/2019\/05\/automatize_a_produ%C3%A7%C3%A3o_de_suas_peti%C3%A7%C3%B5es.png\" alt=\"Automatize a Produ\u00e7\u00e3o de suas Peti\u00e7\u00f5es - Torne sua Advocacia ainda mais inteligente\" width=\"1000\" height=\"276\" class=\"alignnone wp-image-11456 size-full\"><\/a><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quer descobrir como automatizar o preenchimento de todos os seus modelos de peti\u00e7\u00e3o e otimizar o tempo de toda sua equipe? Clique aqui MODELO DE OBRIGA\u00c7\u00c3O DE FAZER EXCELENT\u00cdSSIMO SENHOR DOUTOR JUIZ DE DIREITO DA &#8230; \u00aa VARA C\u00cdVEL (JUIZADO ESPECIAL) DA COMARCA DE CIDADE&#8211;ESTADO &#8230; (nome completo em negrito [&hellip;]<\/p>\n","protected":false},"author":44,"featured_media":11456,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"footnotes":""},"modelo_category":[1457],"class_list":["post-12423","modelos","type-modelos","status-publish","has-post-thumbnail","hentry","modelo_category-direito"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MODELO DE OBRIGA\u00c7\u00c3O DE FAZER<\/title>\n<meta name=\"description\" content=\"Copie aqui sem restri\u00e7\u00f5es e baixe em word seu modelo de obriga\u00e7\u00e3o de fazer\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/advbox.com.br\/blog\/modelos\/obrigacao-de-fazer\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MODELO DE OBRIGA\u00c7\u00c3O DE FAZER\" \/>\n<meta property=\"og:description\" content=\"Copie aqui sem restri\u00e7\u00f5es e baixe em word seu modelo de obriga\u00e7\u00e3o de fazer\" \/>\n<meta property=\"og:url\" content=\"https:\/\/advbox.com.br\/blog\/modelos\/obrigacao-de-fazer\/\" \/>\n<meta property=\"og:site_name\" content=\"Software Jur\u00eddico Completo - ADVBOX\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/advbox\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-07T18:23:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/advbox.com.br\/blog\/wp-content\/uploads\/2019\/05\/automatize_a_produ\u00e7\u00e3o_de_suas_peti\u00e7\u00f5es.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"276\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@advbox2\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/advbox.com.br\/blog\/modelos\/obrigacao-de-fazer\/\",\"url\":\"https:\/\/advbox.com.br\/blog\/modelos\/obrigacao-de-fazer\/\",\"name\":\"MODELO DE OBRIGA\u00c7\u00c3O DE FAZER\",\"isPartOf\":{\"@id\":\"https:\/\/advbox.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/advbox.com.br\/blog\/modelos\/obrigacao-de-fazer\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/advbox.com.br\/blog\/modelos\/obrigacao-de-fazer\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/advbox.com.br\/blog\/wp-content\/uploads\/2019\/05\/automatize_a_produ\u00e7\u00e3o_de_suas_peti\u00e7\u00f5es.png\",\"datePublished\":\"2019-03-07T18:21:59+00:00\",\"dateModified\":\"2025-05-07T18:23:49+00:00\",\"description\":\"Copie aqui sem restri\u00e7\u00f5es e baixe em word seu modelo de obriga\u00e7\u00e3o de fazer\",\"breadcrumb\":{\"@id\":\"https:\/\/advbox.com.br\/blog\/modelos\/obrigacao-de-fazer\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/advbox.com.br\/blog\/modelos\/obrigacao-de-fazer\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/advbox.com.br\/blog\/modelos\/obrigacao-de-fazer\/#primaryimage\",\"url\":\"https:\/\/advbox.com.br\/blog\/wp-content\/uploads\/2019\/05\/automatize_a_produ\u00e7\u00e3o_de_suas_peti\u00e7\u00f5es.png\",\"contentUrl\":\"https:\/\/advbox.com.br\/blog\/wp-content\/uploads\/2019\/05\/automatize_a_produ\u00e7\u00e3o_de_suas_peti\u00e7\u00f5es.png\",\"width\":1000,\"height\":276,\"caption\":\"automatiza\u00e7\u00e3o de peti\u00e7\u00f5es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/advbox.com.br\/blog\/modelos\/obrigacao-de-fazer\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/advbox.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Modelos\",\"item\":\"https:\/\/advbox.com.br\/blog\/modelos\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Modelo de a\u00e7\u00e3o de obriga\u00e7\u00e3o de fazer e inexist\u00eancia de d\u00e9bito (CRLV\/IPVA)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/advbox.com.br\/blog\/#website\",\"url\":\"https:\/\/advbox.com.br\/blog\/\",\"name\":\"Software Jur\u00eddico Completo - ADVBOX\",\"description\":\"Plataforma para Advocacia Digital\",\"publisher\":{\"@id\":\"https:\/\/advbox.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/advbox.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/advbox.com.br\/blog\/#organization\",\"name\":\"ADVBOX Blog - Software jur\u00eddico da advocacia digital\",\"url\":\"https:\/\/advbox.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/advbox.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/advbox.com.br\/blog\/wp-content\/uploads\/2019\/12\/Como-aumentar-a-produtividade_.jpg\",\"contentUrl\":\"https:\/\/advbox.com.br\/blog\/wp-content\/uploads\/2019\/12\/Como-aumentar-a-produtividade_.jpg\",\"width\":320,\"height\":213,\"caption\":\"ADVBOX Blog - Software jur\u00eddico da advocacia digital\"},\"image\":{\"@id\":\"https:\/\/advbox.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/advbox\/\",\"https:\/\/x.com\/advbox2\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MODELO DE OBRIGA\u00c7\u00c3O DE FAZER","description":"Copie aqui sem restri\u00e7\u00f5es e baixe em word seu modelo de obriga\u00e7\u00e3o de fazer","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/advbox.com.br\/blog\/modelos\/obrigacao-de-fazer\/","og_locale":"pt_BR","og_type":"article","og_title":"MODELO DE OBRIGA\u00c7\u00c3O DE FAZER","og_description":"Copie aqui sem restri\u00e7\u00f5es e baixe em word seu modelo de obriga\u00e7\u00e3o de fazer","og_url":"https:\/\/advbox.com.br\/blog\/modelos\/obrigacao-de-fazer\/","og_site_name":"Software Jur\u00eddico Completo - ADVBOX","article_publisher":"https:\/\/www.facebook.com\/advbox\/","article_modified_time":"2025-05-07T18:23:49+00:00","og_image":[{"width":1000,"height":276,"url":"https:\/\/advbox.com.br\/blog\/wp-content\/uploads\/2019\/05\/automatize_a_produ\u00e7\u00e3o_de_suas_peti\u00e7\u00f5es.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@advbox2","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/advbox.com.br\/blog\/modelos\/obrigacao-de-fazer\/","url":"https:\/\/advbox.com.br\/blog\/modelos\/obrigacao-de-fazer\/","name":"MODELO DE OBRIGA\u00c7\u00c3O DE FAZER","isPartOf":{"@id":"https:\/\/advbox.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/advbox.com.br\/blog\/modelos\/obrigacao-de-fazer\/#primaryimage"},"image":{"@id":"https:\/\/advbox.com.br\/blog\/modelos\/obrigacao-de-fazer\/#primaryimage"},"thumbnailUrl":"https:\/\/advbox.com.br\/blog\/wp-content\/uploads\/2019\/05\/automatize_a_produ\u00e7\u00e3o_de_suas_peti\u00e7\u00f5es.png","datePublished":"2019-03-07T18:21:59+00:00","dateModified":"2025-05-07T18:23:49+00:00","description":"Copie aqui sem restri\u00e7\u00f5es e baixe em word seu modelo de obriga\u00e7\u00e3o de fazer","breadcrumb":{"@id":"https:\/\/advbox.com.br\/blog\/modelos\/obrigacao-de-fazer\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/advbox.com.br\/blog\/modelos\/obrigacao-de-fazer\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/advbox.com.br\/blog\/modelos\/obrigacao-de-fazer\/#primaryimage","url":"https:\/\/advbox.com.br\/blog\/wp-content\/uploads\/2019\/05\/automatize_a_produ\u00e7\u00e3o_de_suas_peti\u00e7\u00f5es.png","contentUrl":"https:\/\/advbox.com.br\/blog\/wp-content\/uploads\/2019\/05\/automatize_a_produ\u00e7\u00e3o_de_suas_peti\u00e7\u00f5es.png","width":1000,"height":276,"caption":"automatiza\u00e7\u00e3o de peti\u00e7\u00f5es"},{"@type":"BreadcrumbList","@id":"https:\/\/advbox.com.br\/blog\/modelos\/obrigacao-de-fazer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/advbox.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Modelos","item":"https:\/\/advbox.com.br\/blog\/modelos\/"},{"@type":"ListItem","position":3,"name":"Modelo de a\u00e7\u00e3o de obriga\u00e7\u00e3o de fazer e inexist\u00eancia de d\u00e9bito (CRLV\/IPVA)"}]},{"@type":"WebSite","@id":"https:\/\/advbox.com.br\/blog\/#website","url":"https:\/\/advbox.com.br\/blog\/","name":"Software Jur\u00eddico Completo - ADVBOX","description":"Plataforma para Advocacia Digital","publisher":{"@id":"https:\/\/advbox.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/advbox.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/advbox.com.br\/blog\/#organization","name":"ADVBOX Blog - Software jur\u00eddico da advocacia digital","url":"https:\/\/advbox.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/advbox.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/advbox.com.br\/blog\/wp-content\/uploads\/2019\/12\/Como-aumentar-a-produtividade_.jpg","contentUrl":"https:\/\/advbox.com.br\/blog\/wp-content\/uploads\/2019\/12\/Como-aumentar-a-produtividade_.jpg","width":320,"height":213,"caption":"ADVBOX Blog - Software jur\u00eddico da advocacia digital"},"image":{"@id":"https:\/\/advbox.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/advbox\/","https:\/\/x.com\/advbox2"]}]}},"_links":{"self":[{"href":"https:\/\/advbox.com.br\/blog\/wp-json\/wp\/v2\/modelos\/12423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/advbox.com.br\/blog\/wp-json\/wp\/v2\/modelos"}],"about":[{"href":"https:\/\/advbox.com.br\/blog\/wp-json\/wp\/v2\/types\/modelos"}],"author":[{"embeddable":true,"href":"https:\/\/advbox.com.br\/blog\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/advbox.com.br\/blog\/wp-json\/wp\/v2\/comments?post=12423"}],"version-history":[{"count":3,"href":"https:\/\/advbox.com.br\/blog\/wp-json\/wp\/v2\/modelos\/12423\/revisions"}],"predecessor-version":[{"id":74155,"href":"https:\/\/advbox.com.br\/blog\/wp-json\/wp\/v2\/modelos\/12423\/revisions\/74155"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/advbox.com.br\/blog\/wp-json\/wp\/v2\/media\/11456"}],"wp:attachment":[{"href":"https:\/\/advbox.com.br\/blog\/wp-json\/wp\/v2\/media?parent=12423"}],"wp:term":[{"taxonomy":"modelo_category","embeddable":true,"href":"https:\/\/advbox.com.br\/blog\/wp-json\/wp\/v2\/modelo_category?post=12423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}